{"id":1422,"date":"2025-10-04T22:59:25","date_gmt":"2025-10-04T22:59:25","guid":{"rendered":"https:\/\/www.cinthiacarolina.com\/2cmidia\/?p=1422"},"modified":"2025-10-04T22:59:26","modified_gmt":"2025-10-04T22:59:26","slug":"banco-central-passa-a-bloquear-chaves-pix-usadas-em-golpes-e-fraudes","status":"publish","type":"post","link":"https:\/\/www.cinthiacarolina.com\/2cmidia\/banco-central-passa-a-bloquear-chaves-pix-usadas-em-golpes-e-fraudes\/","title":{"rendered":"Banco Central passa a bloquear chaves Pix usadas em golpes e fraudes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Procedimento pretende ampliar seguran\u00e7a da ferramenta<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1170\" height=\"700\" src=\"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/10\/banco_central_mcajr_abr_0104222281_0.webp\" alt=\"\" class=\"wp-image-1423\" srcset=\"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/10\/banco_central_mcajr_abr_0104222281_0.webp 1170w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/10\/banco_central_mcajr_abr_0104222281_0-570x341.webp 570w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/10\/banco_central_mcajr_abr_0104222281_0-768x459.webp 768w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/10\/banco_central_mcajr_abr_0104222281_0-90x54.webp 90w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/10\/banco_central_mcajr_abr_0104222281_0-320x191.webp 320w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/10\/banco_central_mcajr_abr_0104222281_0-560x335.webp 560w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/10\/banco_central_mcajr_abr_0104222281_0-782x468.webp 782w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/10\/banco_central_mcajr_abr_0104222281_0-1136x680.webp 1136w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><figcaption class=\"wp-element-caption\">\u00a9 Marcello Casal JrAg\u00eancia Brasil<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A partir deste s\u00e1bado (4), o Banco Central (BC) bloquear\u00e1 chaves Pix usadas em golpes e fraudes. O bloqueio ocorrer\u00e1 com base nas informa\u00e7\u00f5es prestadas pelas institui\u00e7\u00f5es financeiras, que atingir\u00e3o as chaves informadas pelas pr\u00f3prias institui\u00e7\u00f5es financeiras que integram o sistema Pix.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1661358&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1661358&amp;o=node\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Segundo o BC, o procedimento pretende fortalecer a seguran\u00e7a do Pix.<\/strong>&nbsp;A novidade foi anunciada na \u00faltima reuni\u00e3o do F\u00f3rum Pix. Comit\u00ea consultivo permanente com cerca de 300 participantes do sistema financeiro e da sociedade civil, o F\u00f3rum Pix tem como objetivo subsidiar o BC na defini\u00e7\u00e3o das regras e dos procedimentos que disciplinam o funcionamento do sistema de transfer\u00eancias instant\u00e2neas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A novidade representa mais um refor\u00e7o nas medidas anunciadas nas \u00faltimas semanas para coibir as fraudes e os golpes no Pix.<\/strong>&nbsp;No in\u00edcio de setembro, o BC limitou a R$ 15 mil as transfer\u00eancias via Pix e TED para institui\u00e7\u00f5es de pagamento, que permitem a movimenta\u00e7\u00e3o de recursos, mas n\u00e3o emprestam,&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2025-09\/bc-endurece-regras-de-seguranca-para-instituicoes-de-pagamento\" target=\"_blank\" rel=\"noreferrer noopener\">n\u00e3o autorizadas pela autarquia a funcionar<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A medida veio ap\u00f3s tr\u00eas opera\u00e7\u00f5es contra a lavagem de dinheiro pelo crime organizado: Carbono Oculto, Quasar e Tank.&nbsp;<strong>Segundo a Pol\u00edcia Federal (PF), as investiga\u00e7\u00f5es alcan\u00e7am mais de R$ 50 bilh\u00f5es em movimenta\u00e7\u00f5es financeiras suspeitas via fintechs (tipo de banco digital).<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Refor\u00e7o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m em setembro, o BC obrigou institui\u00e7\u00f5es de pagamentos a&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/radioagencia-nacional\/economia\/audio\/2025-09\/banco-central-obriga-bloqueio-de-transacoes-suspeitas-de-fraude\" target=\"_blank\" rel=\"noreferrer noopener\">negar transa\u00e7\u00f5es para contas suspeitas de fraudes<\/a>. As medidas t\u00eam de ser implementadas at\u00e9 13 de outubro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>As institui\u00e7\u00f5es devem usar informa\u00e7\u00f5es de sistemas eletr\u00f4nicos e bases de dados p\u00fablicos ou privados para fundamentar a suspeita.<\/strong>&nbsp;O dono da conta que receberia o dinheiro deve ser informado sobre a rejei\u00e7\u00e3o da transfer\u00eancia pela institui\u00e7\u00e3o em que tem a conta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, desde quarta-feira (1\u00ba), o BC obrigou as institui\u00e7\u00f5es financeiras a oferecer, em seus aplicativos, o&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2025-10\/botao-de-contestacao-do-pix-esta-disponivel-aos-usuarios\" target=\"_blank\" rel=\"noreferrer noopener\">bot\u00e3o de contesta\u00e7\u00e3o de transa\u00e7\u00f5es do Pix<\/a>. A medida tornou 100% digital o atendimento do&nbsp;Mecanismo Especial de Devolu\u00e7\u00e3o (MED), criado em 2021 para ressarcir v\u00edtimas de fraudes e de golpes no Pix.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Via Ag\u00eancia Brasil Edi\u00e7\u00e3o Fernando Fraga<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Procedimento pretende ampliar seguran\u00e7a da ferramenta A partir deste s\u00e1bado (4), o Banco Central (BC) bloquear\u00e1 chaves Pix&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[2],"tags":[48,47],"location":[],"class_list":["post-1422","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-economia","tag-pix"],"_links":{"self":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/comments?post=1422"}],"version-history":[{"count":1,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1422\/revisions"}],"predecessor-version":[{"id":1424,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1422\/revisions\/1424"}],"wp:attachment":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/media?parent=1422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/categories?post=1422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/tags?post=1422"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/location?post=1422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}