{"id":1397,"date":"2025-10-02T12:25:31","date_gmt":"2025-10-02T12:25:31","guid":{"rendered":"https:\/\/www.cinthiacarolina.com\/2cmidia\/?p=1397"},"modified":"2025-10-04T23:12:00","modified_gmt":"2025-10-04T23:12:00","slug":"o-gesto-de-amor-de-laura-pausini-regravacao-de-gianluca-grignani-ganha-versao-em-portugues-de-ana-carolina-e-vira-destaque","status":"publish","type":"post","link":"https:\/\/www.cinthiacarolina.com\/2cmidia\/o-gesto-de-amor-de-laura-pausini-regravacao-de-gianluca-grignani-ganha-versao-em-portugues-de-ana-carolina-e-vira-destaque\/","title":{"rendered":"O Gesto de Amor de Laura Pausini: Regrava\u00e7\u00e3o de Gianluca Grignani Ganha Vers\u00e3o em Portugu\u00eas de Ana Carolina e Vira Destaque"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"548\" height=\"730\" src=\"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/laura1-548x730.jpg\" alt=\"\" class=\"wp-image-1398\" srcset=\"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/laura1-548x730.jpg 548w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/laura1-308x410.jpg 308w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/laura1-768x1024.jpg 768w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/laura1-1152x1536.jpg 1152w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/laura1-90x120.jpg 90w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/laura1-320x427.jpg 320w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/laura1-560x747.jpg 560w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/laura1-782x1043.jpg 782w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/laura1-1136x1515.jpg 1136w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/laura1.jpg 1440w\" sizes=\"(max-width: 548px) 100vw, 548px\" \/><figcaption class=\"wp-element-caption\">Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">A diva da m\u00fasica italiana Laura Pausini est\u00e1 de volta aos holofotes com um projeto que celebra a sua paix\u00e3o pela can\u00e7\u00e3o italiana e, em especial, seu forte la\u00e7o com o Brasil. Seu novo single, &#8220;La Mia Storia Tra Le Dita&#8221;, \u00e9 uma poderosa releitura do cl\u00e1ssico de 1994, originalmente gravado por Gianluca Grignani. O lan\u00e7amento, por\u00e9m, vem com um presente especial para os f\u00e3s brasileiros: uma vers\u00e3o em portugu\u00eas, &#8220;Quem de N\u00f3s Dois&#8221;, adaptada pela aclamada cantora e compositora Ana Carolina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u200b<strong>Um Cl\u00e1ssico em Quatro Idiomas e uma Homenagem a Ana Carolina<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u200bO lan\u00e7amento de Pausini \u00e9 o primeiro single de seu aguardado novo \u00e1lbum, &#8220;Io Canto 2&#8221;, que segue o conceito de seu sucesso de 2006, &#8220;Io Canto&#8221;, onde a artista reinterpreta grandes sucessos da m\u00fasica italiana. Desta vez, a homenagem ultrapassa as fronteiras da It\u00e1lia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u200bA m\u00fasica, que se tornou um sucesso estrondoso no Brasil na voz de Ana Carolina em 2001 e fez parte de trilhas sonoras de novelas, foi gravada por Pausini em quatro idiomas: italiano, espanhol, franc\u00eas e portugu\u00eas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u200bEm entrevistas, a cantora italiana fez quest\u00e3o de ressaltar que a vers\u00e3o em portugu\u00eas, com letra de Ana Carolina, foi a principal motiva\u00e7\u00e3o para a escolha da can\u00e7\u00e3o. &#8220;A Ana Carolina deu um toque \u00fanico \u00e0 letra, diferente do original, e eu quis homenage\u00e1-la, assim como a Gianluca Grignani,&#8221; explicou Pausini, declarando-se f\u00e3 da brasileira. A vers\u00e3o em portugu\u00eas de Ana Carolina se distingue do original, utilizando apenas a mesma melodia, mas criando uma nova narrativa l\u00edrica que tocou profundamente a artista italiana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u200bApesar da celebra\u00e7\u00e3o, o lan\u00e7amento gerou uma pequena pol\u00eamica na It\u00e1lia. Gianluca Grignani emitiu uma advert\u00eancia formal \u00e0 cantora, citando desrespeito por n\u00e3o ter sido mencionado nas primeiras publica\u00e7\u00f5es de Pausini e por altera\u00e7\u00f5es na letra original em outras vers\u00f5es, que, segundo ele, distorceram o significado da obra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u200b&#8221;Na Outra Vida Eu Era Brasileira&#8221;: Turn\u00ea Mundial e Show Hist\u00f3rico no Brasil<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u200bO lan\u00e7amento do single e do projeto &#8220;Io Canto 2&#8221; \u00e9 o aquecimento para a &#8220;Io Canto \/ Yo Canto World Tour 2026\/2027&#8221;, que levar\u00e1 Laura Pausini de volta aos palcos de todo o mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u200bRefor\u00e7ando sua hist\u00f3rica conex\u00e3o afetiva com o Brasil \u2014 a ponto de brincar dizendo que &#8220;na outra vida era brasileira&#8221; \u2014, a artista confirmou uma data hist\u00f3rica no pa\u00eds. Pela primeira vez em sua carreira, Laura Pausini far\u00e1 um show em um est\u00e1dio em S\u00e3o Paulo: a apresenta\u00e7\u00e3o est\u00e1 marcada para 27 de fevereiro de 2027 na Mercado Livre Arena Pacaembu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u200bA turn\u00ea, que tem previs\u00e3o de in\u00edcio em 2026, ser\u00e1 a oportunidade para os f\u00e3s brasileiros ouvirem a vers\u00e3o de &#8220;Quem de N\u00f3s Dois&#8221; diretamente da voz da diva italiana, consolidando a ponte musical entre a It\u00e1lia e o Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ansiosos por mais este lan\u00e7amento da diva?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reportagem: Cinth\u00eda C\u00e4rol\u00edna<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A diva da m\u00fasica italiana Laura Pausini est\u00e1 de volta aos holofotes com um projeto que celebra a&#8230;<\/p>","protected":false},"author":1,"featured_media":1398,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[4],"tags":[36,27],"location":[],"class_list":["post-1397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-laura-pausini","tag-musica"],"_links":{"self":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/comments?post=1397"}],"version-history":[{"count":3,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1397\/revisions"}],"predecessor-version":[{"id":1429,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1397\/revisions\/1429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/media\/1398"}],"wp:attachment":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/media?parent=1397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/categories?post=1397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/tags?post=1397"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/location?post=1397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}