{"id":1383,"date":"2025-09-27T18:21:50","date_gmt":"2025-09-27T18:21:50","guid":{"rendered":"https:\/\/www.cinthiacarolina.com\/2cmidia\/?p=1383"},"modified":"2025-09-27T18:21:52","modified_gmt":"2025-09-27T18:21:52","slug":"rio-ganha-mais-opcoes-gastronomicas-com-mercado-em-laranjeiras","status":"publish","type":"post","link":"https:\/\/www.cinthiacarolina.com\/2cmidia\/rio-ganha-mais-opcoes-gastronomicas-com-mercado-em-laranjeiras\/","title":{"rendered":"Rio ganha mais op\u00e7\u00f5es gastron\u00f4micas com mercado em Laranjeiras"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Investimento na revitaliza\u00e7\u00e3o foi de R$ 10 milh\u00f5es<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1170\" height=\"700\" src=\"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/rbr8960.jpg\" alt=\"\" class=\"wp-image-1384\" srcset=\"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/rbr8960.jpg 1170w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/rbr8960-570x341.jpg 570w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/rbr8960-768x459.jpg 768w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/rbr8960-90x54.jpg 90w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/rbr8960-320x191.jpg 320w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/rbr8960-560x335.jpg 560w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/rbr8960-782x468.jpg 782w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/rbr8960-1136x680.jpg 1136w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><figcaption class=\"wp-element-caption\">\u00a9 T\u00e2nia R\u00eago\/Ag\u00eancia Brasil<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acompanhado do seu cachorro&nbsp;<em>Z\u00e9<\/em>, o empres\u00e1rio aposentado Luis S\u00e9rgio Santos, de 73 anos, esteve esta semana no rec\u00e9m-inaugurado Novo Mercado S\u00e3o Jos\u00e9. Ele queria ver as novidades do tradicional polo gastron\u00f4mico e cultural de Laranjeiras, na zona sul do Rio de Janeiro, fechado desde 2018.&nbsp;<\/strong><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1660280&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1660280&amp;o=node\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santos conta que frequentava o espa\u00e7o antes de seu fechamento. &#8220;Em rela\u00e7\u00e3o ao que est\u00e1 agora, era um im\u00f3vel com caracter\u00edsticas muito antigas, estilo colonial, era aconchegante, mas a gente via que estava precisando de uma reforma. Tinha barzinhos e venda de salgadinhos. Ouvia-se m\u00fasica, tocavam viol\u00e3o, tomavam um chopinho. Mas estava abandonado. Agora est\u00e1 mais confort\u00e1vel, moderno, bonito, bem estruturado. Voltarei a frequentar. Ser\u00e1 excepcional se tiver uma programa\u00e7\u00e3o musical&#8221;, enfatiza.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Reduto gastron\u00f4mico<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A farmac\u00eautica Luiza Gotin, de 39 anos, aproveitou um tempo livre no trabalho para conhecer o novo reduto gastron\u00f4mico do Rio. Moradora de Laranjeiras desde 2020, ela s\u00f3 conheceu o im\u00f3vel abandonado.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Eu passava por aqui e via o mercado bem destru\u00eddo, com moradores de rua dormindo dentro e fora do local. Fiquei muito feliz quando pensaram em revitalizar porque trouxe, al\u00e9m de mais seguran\u00e7a, espa\u00e7o de intera\u00e7\u00e3o com restaurantes. Espero que tenha atividades culturais. \u00c9 um pr\u00e9dio t\u00e3o ic\u00f4nico que n\u00e3o podia ficar abandonado do jeito que estava. Foi um presente para o Rio&#8221;,&nbsp;opinou Luiza.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fechado h\u00e1 sete anos, quando o Instituto Nacional do Seguro Social (INSS) retomou judicialmente o im\u00f3vel, a prefeitura do Rio comprou o pr\u00e9dio e o terreno ao lado, em 2023, por R$ 3 milh\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A Companhia Carioca de Parcerias e Investimentos (CCPar) fez uma chamada p\u00fablica e o cons\u00f3rcio liderado pela Engeprat&nbsp;com a curadoria da Junta Local, que re\u00fane produtores de org\u00e2nicos, foi selecionado para gerir o espa\u00e7o pelos pr\u00f3ximos 25 anos. O investimento privado na revitaliza\u00e7\u00e3o foi de R$ 10 milh\u00f5es.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Popularmente conhecido como Mercadinho S\u00e3o Jos\u00e9, o centro gastron\u00f4mico voltou a funcionar com 16 empreendimentos, entre hortifruti org\u00e2nico, queijaria, confeitaria autoral, cozinha \u00e1rabe, caf\u00e9 especial, massas artesanais, sorvetes veganos, fermentados, bares e restaurantes. O mercado fica aberto de ter\u00e7a-feira a domingo, das 10h \u00e0s 22h, na Rua das Laranjeiras, 90.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Massas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O espa\u00e7o foi uma oportunidade para que pequenos neg\u00f3cios abrissem lojas f\u00edsicas pela primeira vez.<strong>&nbsp;O restaurante Basta, especializado em massas, \u00e9 um deles. Mauricio Borges, de 28 anos, fez o curso de gastronomia na renomada escola&nbsp;<em>Le Cordon Bleu<\/em>. A s\u00f3cia, Ellen Gonzalez, foi professora dele na escola de gastronomia francesa.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;A Ellen sempre participou da Junta Local e, quando soube que ia reabrir o mercado, ela se interessou e abrimos aqui nosso primeiro neg\u00f3cio. Tem ficado bem cheio. Nossa expectativa \u00e9 muito boa. Estamos aumentando a nossa equipe e contratando mais gente&#8221;, revela.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outro estreante \u00e9 o Rancho das Vertentes, queijaria com produtos artesanais pr\u00f3prios e de outros produtores. A s\u00f3cia Sandra Cardoso, de 59 anos, conta que vendiam muitos dos seus produtos nas feiras da Junta Local. &#8220;H\u00e1 muito tempo a gente estava procurando um ponto para abrir uma loja f\u00edsica.&nbsp; Era um sonho ter uma loja de produtor de queijo artesanal. Tem sido bem movimentado e estamos vendendo bem&#8221;, avalia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cofundador da Junta Local, Thiago Nasser, disse que a ideia era voltar a ser um mercado com produtores locais como era quando foi fundado em 1944. &#8220;A ideia era resgatar essa tradi\u00e7\u00e3o de ser um lugar de produtores. Quando a gente come\u00e7ou com a prospec\u00e7\u00e3o, a gente trabalhou com a nossa rede de produtores para ter um lugar fixo. J\u00e1 geramos cerca de 150 empregos&#8221;, afirmou Nasser.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde 1944, o mercado integrou um ciclo de espa\u00e7os comunit\u00e1rios cariocas batizados com nomes de santos \u2013 S\u00e3o Sebasti\u00e3o, S\u00e3o Bento, S\u00e3o Rafael, S\u00e3o Lucas e S\u00e3o Paulo. Seu tombamento como Patrim\u00f4nio Cultural do Rio, em 1994, refor\u00e7ou o valor como patrim\u00f4nio afetivo e arquitet\u00f4nico da cidade, segundo a prefeitura.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Senzala e celeiro<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O im\u00f3vel foi uma senzala e um celeiro de uma fazenda localizada no Parque Guinle na \u00e9poca do Imp\u00e9rio.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sua inaugura\u00e7\u00e3o como mercado ocorreu em 31 de maio de 1944, quando o presidente Get\u00falio Vargas decidiu adaptar as baias para criar um local que pudesse fornecer alimentos mais acess\u00edveis \u00e0 popula\u00e7\u00e3o durante a Segunda Guerra Mundial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depois de d\u00e9cadas de abandono desde os anos 1960, o mercado passou por uma revitaliza\u00e7\u00e3o em 1988 e se tornou um ponto tradicional da boemia carioca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, com o passar dos anos, a infraestrutura do local come\u00e7ou a se deteriorar e ele acabou fechado em 2018, ap\u00f3s o INSS retomar o local.&nbsp;Agora, a realidade \u00e9 outra.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reportagem: <strong>Ana Cristina Campos &#8211; Rep\u00f3rter da Ag\u00eancia Brasil<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Edi\u00e7\u00e3o: Edi\u00e7\u00e3o: Kleber Sampaio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Investimento na revitaliza\u00e7\u00e3o foi de R$ 10 milh\u00f5es Acompanhado do seu cachorro&nbsp;Z\u00e9, o empres\u00e1rio aposentado Luis S\u00e9rgio Santos,&#8230;<\/p>","protected":false},"author":1,"featured_media":1384,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[2],"tags":[],"location":[],"class_list":["post-1383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/comments?post=1383"}],"version-history":[{"count":1,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1383\/revisions"}],"predecessor-version":[{"id":1385,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1383\/revisions\/1385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/media\/1384"}],"wp:attachment":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/media?parent=1383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/categories?post=1383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/tags?post=1383"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/location?post=1383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}