{"id":1377,"date":"2025-09-27T18:10:49","date_gmt":"2025-09-27T18:10:49","guid":{"rendered":"https:\/\/www.cinthiacarolina.com\/2cmidia\/?p=1377"},"modified":"2025-09-27T18:10:50","modified_gmt":"2025-09-27T18:10:50","slug":"jovens-de-comunidade-periferica-do-recife-tocarao-para-o-papa-leao","status":"publish","type":"post","link":"https:\/\/www.cinthiacarolina.com\/2cmidia\/jovens-de-comunidade-periferica-do-recife-tocarao-para-o-papa-leao\/","title":{"rendered":"Jovens de comunidade perif\u00e9rica do Recife tocar\u00e3o para o Papa Le\u00e3o"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Orquestra Crian\u00e7a Cidad\u00e3 criou novos acordes na comunidade do Coque<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1170\" height=\"700\" src=\"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/54776620511_a3e1b0c65d_o.jpg\" alt=\"\" class=\"wp-image-1378\" srcset=\"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/54776620511_a3e1b0c65d_o.jpg 1170w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/54776620511_a3e1b0c65d_o-570x341.jpg 570w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/54776620511_a3e1b0c65d_o-768x459.jpg 768w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/54776620511_a3e1b0c65d_o-90x54.jpg 90w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/54776620511_a3e1b0c65d_o-320x191.jpg 320w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/54776620511_a3e1b0c65d_o-560x335.jpg 560w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/54776620511_a3e1b0c65d_o-782x468.jpg 782w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/54776620511_a3e1b0c65d_o-1136x680.jpg 1136w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><figcaption class=\"wp-element-caption\">Augusto Cataldi &#8211; Ascom OCC<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A vassoura, como o corpo do violoncelo. O l\u00e1pis, como o arco que desliza sobre as cordas. Na imagina\u00e7\u00e3o da pernambucana Callyandra Santos, a m\u00fasica na cabe\u00e7a obstru\u00eda at\u00e9 os sons dos tiros nas ruas do bairro do Coque, uma das regi\u00f5es mais violentas &#8211; e estigmatizadas &#8211; do Recife (PE). Na \u00e9poca, aos 9 anos,&nbsp;ela havia ingressado na Orquestra Crian\u00e7a Cidad\u00e3, um projeto sem fins lucrativos pelo qual j\u00e1 passaram mais de mil crian\u00e7as e adolescentes como ela. Novos acordes entraram pela janela da comunidade que, em 2006, tinha o menor IDH da capital pernambucana.&nbsp;<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1660307&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1660307&amp;o=node\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hoje, aos 17 ano, Callyandra foi uma das 11 selecionadas da orquestra de jovens do Recife para tocar fora do pa\u00eds em uma turn\u00ea pela \u00c1sia e Europa. Eles estar\u00e3o acompanhados de m\u00fasicos de pa\u00edses em guerra, como palestinos e israelenses, ucranianos e russos, al\u00e9m de coreanos do Sul e do Norte.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A turn\u00ea do que est\u00e1 sendo chamado de \u201cConcerto pela Paz\u201d prev\u00ea apresenta\u00e7\u00f5es em Seul (na Coreia do Sul, na ter\u00e7a, dia 30), em Hiroshima e Osaka (Jap\u00e3o, nos dia 4 e 5 de outubro), em Roma (It\u00e1lia, no dia 7) e no Vaticano para o Papa (no dia 8).<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&#8220;Nada foi em v\u00e3o&#8221;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Na hist\u00f3ria de Callyandra, como na de seus colegas, nada foi simples. A m\u00e3e, Sara Coutinho, de 47 anos, trabalha todas as madrugadas em uma f\u00e1brica de refrigerante situada a mais de uma hora de casa.&nbsp;Ela tem direito a apenas uma folga por semana e s\u00f3 consegue ouvir a filha ensaiar na hora do almo\u00e7o &#8211; enquanto a menina treina com o violoncelo, a m\u00e3e consegue descansar com esse novo som. \u201c\u00c9 uma oportunidade \u00fanica na vida. Fico muito orgulhosa\u201d, diz a m\u00e3e.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sara \u00e9 m\u00e3e solo e soube da orquestra pelo sobrinho, Davi Andrade, que come\u00e7ou no projeto aos 7 anos de idade. Ele formou-se em m\u00fasica na Universidade Federal de Pernambuco (UFPE) e hoje, aos 26, \u00e9 professor. Davi tamb\u00e9m far\u00e1 a turn\u00ea. Os vizinhos dele j\u00e1 se acostumaram com a trilha sonora na porta de casa.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cNa m\u00fasica, o meu primo Davi foi quem mais me inspirou. Ele virou tamb\u00e9m meu professor\u201d, garante Callyandra.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Ao testemunhar a trajet\u00f3ria do rapaz, a menina tamb\u00e9m pretende seguir as linhas de suas partituras: ir para a faculdade no ano que vem cursar m\u00fasica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na vida, a luta di\u00e1ria da m\u00e3e e a lembran\u00e7a da av\u00f3, que morreu durante a pandemia de Covid, em 2020, inspiram a garota e fazem com que ela respire fundo na hora de tocar.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cEu quero mostrar para elas que nada foi em v\u00e3o\u201d, diz Callyandra.<br>&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Bach de encher os olhos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Entre tantas m\u00fasicas que j\u00e1 passaram por suas jovens cordas, a \u201cSu\u00edte para violoncelo N\u00ba 1\u201d, de Johann Sebastian Bach, faz a menina do Coque encher os olhos de l\u00e1grimas, enquanto faz o arco se mover entre o presente, o passado e o que quer para o futuro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Davi, o primo e inspira\u00e7\u00e3o da Callyandra, recorda que aprendeu o violoncelo com o instrumento apoiado, mesmo ainda sem conseguir pisar no ch\u00e3o de t\u00e3o pequeno que era em compara\u00e7\u00e3o com o equipamento.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cCom 13 anos de idade, eu vi que seria a minha profiss\u00e3o porque mudou a minha hist\u00f3ria e da minha fam\u00edlia\u201d.&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Era na sede da orquestra que ele fazia as tr\u00eas refei\u00e7\u00f5es do dia, em um quartel do Ex\u00e9rcito (7\u00ba Dep\u00f3sito de Suprimento), institui\u00e7\u00e3o com o qual o projeto de m\u00fasica tem parceria. Na adolesc\u00eancia, o rapaz tocou diante do Papa Francisco.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com apenas 19 anos de idade, virou professor no n\u00facleo da orquestra em uma \u00e1rea rural da cidade de Igarassu (PE). L\u00e1, ele ensina m\u00fasica para adolescentes que, durante o dia, trabalham na ro\u00e7a com os pais.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEu me identifico com eles. Me vejo neles\u201d. Al\u00e9m de Igarassu e Recife, jovens em vulnerabilidade na cidade de Ipojuca, no litoral sul, tamb\u00e9m t\u00eam chances de aprender. Ao todo, s\u00e3o 400 alunos nas tr\u00eas unidades do projeto. Para ele, t\u00e3o importante quanto as notas musicais \u00e9 a solidariedade que chega em sons e gestos, entre os mestres, os jovens e os m\u00fasicos. Um impulsiona o outro a n\u00e3o desistir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00fasica de paz<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Enquanto toca o concerto para violoncelo do tcheco Anton\u00edn Dvor\u00e1k (1841 &#8211; 1904) na porta de casa no Coque, Davi lamenta que perdeu amigos para a viol\u00eancia do bairro, antes tomado por fac\u00e7\u00f5es.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cA gente tinha na orquestra filhos de pais de fac\u00e7\u00f5es diferentes. A m\u00fasica ajudou a estabelecer a paz muitas vezes\u201d, afirma o m\u00fasico.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Ele entende que a orquestra ensina mais do que m\u00fasica. \u201cA orquestra literalmente tem um aspecto social no Coque muito importante que n\u00e3o cabe nos n\u00fameros. Ensina cidadania\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O projeto da orquestra foi criado h\u00e1 19 anos pelo juiz de direito Jo\u00e3o Targino, do Tribunal de Justi\u00e7a de Pernambuco (TJPE).&nbsp;Depois de integrar o Programa Crian\u00e7a Cidad\u00e3, que atuava em prol de pessoas em situa\u00e7\u00e3o de rua, o magistrado optou por criar um coral. Das vozes aos instrumentos, foi uma nova ousadia.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cN\u00f3s escolhemos a comunidade do Coque porque tinha os piores \u00edndices de desenvolvimento humano e o maior \u00edndice de viol\u00eancia\u201d, recorda.&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">O maestro Jos\u00e9 Renato Accioly, de 59 anos, diz que reunir jovens de culturas t\u00e3o diferentes \u00e9 desafiador, mas mostra como a m\u00fasica tem linguagem universal. Ele explica que o repert\u00f3rio vai contemplar m\u00fasicas das diferentes nacionalidades. E, claro, inclui o frevo e medley de m\u00fasicas brasileiras.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cS\u00e3o m\u00fasicos de alt\u00edssimo n\u00edvel. Independentemente se v\u00e3o querer seguir na m\u00fasica, eles nunca esquecer\u00e3o dessa oportunidade que tiveram de estar nessa orquestra\u201d.&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Sotaque alem\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um dos m\u00fasicos experientes que tocar\u00e1 na turn\u00ea \u00e9 o contrabaixista Antonino Tertuliano, de 32 anos. Ele tamb\u00e9m nasceu no Coque e ingressou na orquestra quando tinha apenas 14 anos.&nbsp;Hoje, mora na Alemanha e \u00e9 integrante da Niederbayerische Philharmonie Orchester (a orquestra filarm\u00f4nica da Baixa Baviera). Ele \u00e9 um entusiasta do projeto e faz parte da organiza\u00e7\u00e3o dos eventos internacionais.&nbsp;\u201cO significado que o Crian\u00e7a Cidad\u00e3 tem para mim \u00e9 enorme. Eu tenho imensa gratid\u00e3o\u201d, disse, em entrevista \u00e0<strong>&nbsp;Ag\u00eancia Brasil<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sempre que est\u00e1 no Brasil , visita os antigos mestres e os novos alunos. \u201cApresento aos jovens a minha realidade atual e digo que \u00e9 poss\u00edvel conquistar o mundo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Emocionado, recordou que, quando ingressou no projeto, n\u00e3o tinha conhecimento de m\u00fasica. Aluno de uma escola p\u00fablica local, se encantou depois que fez um teste de aptid\u00e3o musical.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cO projeto remoldou o bairro e a comunidade. Esse projeto social apresentou n\u00e3o s\u00f3 uma profiss\u00e3o,&nbsp; mas outra perspectiva de futuro\u201d.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">\u201cEra dif\u00edcil criar filho no Coque\u201d<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um dos jovens que chegou para o projeto e depois virou violoncelista foi Cleybson da Silva, de 21 anos. Chegou ao projeto com 13 anos e, em 2020, perdeu a m\u00e3e para a Covid. \u201cA m\u00fasica mudou totalmente o rumo da minha vida\u201d, afirma Clebson, que hoje cursa licenciatura em m\u00fasica na UFPE. O pai, Clayton Oliveira, de 44, trabalha com instala\u00e7\u00e3o de c\u00e2meras de seguran\u00e7a.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cAntigamente, era bem dif\u00edcil criar um filho no Coque. Era muito perigoso mesmo. A gente ouvia tiroteio sempre\u201d, lembra Clayton.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Os barulhos mudaram. Para ele a transforma\u00e7\u00e3o do local tem direta rela\u00e7\u00e3o com a orquestra. O pai est\u00e1 orgulhoso porque o filho mais novo, Bernardo, de 7 anos, tamb\u00e9m j\u00e1 come\u00e7ou na orquestra.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 Ana Clara Gomes, de 17 anos, se apaixonou pela viola quando estava na igreja evang\u00e9lica que frequenta. Foi amor ao primeiro som. Tanto que passou a desenhar at\u00e9 na parede as notas musicais desde crian\u00e7a. O cen\u00e1rio de sua vida tem a paisagem do sub\u00farbio, dos telhados com falhas e fios embolados nos postes de luz.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando soube que teria a primeira oportunidade de viajar para fora do Brasil, teve cinco dias para ensaiar m\u00fasica do compositor Camargo Guarnieri (1907 &#8211; 1993).&nbsp; \u201cEu fiquei estudando sem parar\u201d. A primeira musicista da fam\u00edlia foi criada pela m\u00e3e, que \u00e9 t\u00e9cnica de enfermagem, e viu na m\u00fasica uma chance de felicidade depois que o pai morreu, h\u00e1 oito anos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e1 um ano, Ana conseguiu comprar, em presta\u00e7\u00f5es, o pr\u00f3prio instrumento. E pensar que no come\u00e7o, o que fazia o papel da viola era a caixa de sab\u00e3o em p\u00f3, a fim de sentir o peso do novo instrumento.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sab\u00e3o em p\u00f3<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O violinista Pedro Martins, de 21 anos, tamb\u00e9m utilizou a caixa de sab\u00e3o em p\u00f3, como se fosse o instrumento, e o l\u00e1pis, como se fosse o arco. \u201cSe n\u00e3o segurar o violino direito, a m\u00fasica sai diferente\u201d. Ele teve gosto pela m\u00fasica ouvindo o pai, que \u00e9 motorista de aplicativo, tocando viol\u00e3o na sala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para imaginar a m\u00fasica, levava CD para casa para tocar no antigo aparelho de som. Quando come\u00e7ou, n\u00e3o tinha computador em casa, nem celular.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cTransformava a pequena sala de casa no meu palco. Meus pais tinham que me ouvir\u201d, lembra Pedro.&nbsp;&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">O pai, George Silva, de 41 anos, orgulhoso, recorda que mudava os hor\u00e1rios do trabalho para aplaudir o filh\u00e3o, que cursa m\u00fasica na UFPE. \u201cEle n\u00e3o se envolveu com coisa errada. Ele n\u00e3o mexia no viol\u00e3o da igreja. Quem diria que agora vai viajar o mundo por a\u00ed. Eu nunca passei nem perto de um avi\u00e3o ou de faculdade\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O pai lamenta que perdeu um irm\u00e3o, cunhado e amigos para \u201ccoisas erradas\u201d, particularmente o envolvimento com drogas. O filho toca violino e ele v\u00ea o bairro de antes ficar cada vez mais distante. O Coque, as dificuldades de todos os dias, a esperan\u00e7a que bateu \u00e0 porta dos vizinhos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O mundo virou outro e nem precisou de avi\u00e3o. Come\u00e7ou com uma caixa de sab\u00e3o em p\u00f3.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cCada vez que eu toco, eu penso nos meus pais e o quanto eles insistiram. Hoje nossa fam\u00edlia se sente nas nuvens\u201d, disse o violinista antes do embarque.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Reportagem: <strong>Luiz Cl\u00e1udio Ferreira &#8211; Rep\u00f3rter da Ag\u00eancia Brasil<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Edi\u00e7\u00e3o: Amanda Cieglinski<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Orquestra Crian\u00e7a Cidad\u00e3 criou novos acordes na comunidade do Coque A vassoura, como o corpo do violoncelo. O&#8230;<\/p>","protected":false},"author":1,"featured_media":1378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[4],"tags":[27,26],"location":[],"class_list":["post-1377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-musica","tag-projeto-social"],"_links":{"self":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/comments?post=1377"}],"version-history":[{"count":1,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1377\/revisions"}],"predecessor-version":[{"id":1379,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1377\/revisions\/1379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/media\/1378"}],"wp:attachment":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/media?parent=1377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/categories?post=1377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/tags?post=1377"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/location?post=1377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}