{"id":1374,"date":"2025-09-27T18:02:42","date_gmt":"2025-09-27T18:02:42","guid":{"rendered":"https:\/\/www.cinthiacarolina.com\/2cmidia\/?p=1374"},"modified":"2025-09-27T18:02:43","modified_gmt":"2025-09-27T18:02:43","slug":"transporte-melhor-lugar-de-crianca-no-carro-e-o-meio-do-banco-de-tras","status":"publish","type":"post","link":"https:\/\/www.cinthiacarolina.com\/2cmidia\/transporte-melhor-lugar-de-crianca-no-carro-e-o-meio-do-banco-de-tras\/","title":{"rendered":"Transporte: melhor lugar de crian\u00e7a no carro \u00e9 o meio do banco de tr\u00e1s"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Essa atitude pode aumentar em 24% a seguran\u00e7a do menor<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1170\" height=\"700\" src=\"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/dia-do-cicilista1_mcamgo_abr_190820221818-5.webp\" alt=\"\" class=\"wp-image-1375\" srcset=\"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/dia-do-cicilista1_mcamgo_abr_190820221818-5.webp 1170w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/dia-do-cicilista1_mcamgo_abr_190820221818-5-570x341.webp 570w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/dia-do-cicilista1_mcamgo_abr_190820221818-5-768x459.webp 768w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/dia-do-cicilista1_mcamgo_abr_190820221818-5-90x54.webp 90w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/dia-do-cicilista1_mcamgo_abr_190820221818-5-320x191.webp 320w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/dia-do-cicilista1_mcamgo_abr_190820221818-5-560x335.webp 560w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/dia-do-cicilista1_mcamgo_abr_190820221818-5-782x468.webp 782w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/dia-do-cicilista1_mcamgo_abr_190820221818-5-1136x680.webp 1136w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><figcaption class=\"wp-element-caption\">Marcelo Camargo- Ag\u00eancia Brasil<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O melhor local para instalar um dispositivo de seguran\u00e7a para o transporte de crian\u00e7as \u00e9 o meio do banco de tr\u00e1s do ve\u00edculo.&nbsp;<strong>De acordo com o diretor cient\u00edfico da Associa\u00e7\u00e3o Brasileira de Medicina do Tr\u00e1fego (Abramet), Flavio Adura, transportar a crian\u00e7a no centro do banco traseiro pode aumentar em 24% a seguran\u00e7a do menor.<\/strong><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1660496&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1660496&amp;o=node\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante o 16\u00ba Congresso Brasileiro de Medicina do Tr\u00e1fego, em Salvador, ele destacou que n\u00e3o h\u00e1 diferen\u00e7a significativa quanto ao risco entre o posicionamento da crian\u00e7a no lado direito ou no lado esquerdo do banco de tr\u00e1s do ve\u00edculo. Al\u00e9m disso, a escolha correta do dispositivo pode reduzir em 60% o risco de morte de crian\u00e7as em acidentes de tr\u00e2nsito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Adura lembrou ainda que crian\u00e7as s\u00f3 devem andar no banco da frente a partir dos 10 anos ou ao atingirem altura m\u00ednima de 1,45 metro, quando j\u00e1 n\u00e3o necessitam de nenhum tipo de dispositivo.<\/strong>&nbsp;As exce\u00e7\u00f5es incluem casos onde o carro s\u00f3 conta com o banco dianteiro e casos onde todos os assentos do banco de tr\u00e1s j\u00e1 est\u00e3o ocupados por crian\u00e7as.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cNessas situa\u00e7\u00f5es, o dispositivo de seguran\u00e7a apropriado para a idade deve ser mantido, o airbag do passageiro da frente deve ser desligado e o banco deve ser ajustado o m\u00e1ximo poss\u00edvel para tr\u00e1s\u201d, explicou. Em carros com quatro crian\u00e7as, a mais alta e n\u00e3o necessariamente a mais velha deve ser transportada no banco da frente.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">O diretor cient\u00edfico da Abramet destacou tamb\u00e9m que, em carros fabricados antes de 1988 e que n\u00e3o tem cinto de tr\u00eas pontos no banco de tr\u00e1s, a orienta\u00e7\u00e3o \u00e9 transportar a crian\u00e7a no banco da frente, onde o cinto de tr\u00eas pontos est\u00e1 dispon\u00edvel, utilizando o dispositivo apropriado para a idade e mantendo as orienta\u00e7\u00f5es de desligar o airbag e recuar o banco o m\u00e1ximo poss\u00edvel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>*A rep\u00f3rter viajou a convite da Associa\u00e7\u00e3o Brasileira de Medicina do Tr\u00e1fego (Abramet)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reportagem: <strong>Paula Laboissi\u00e8re &#8211; Enviada especial*<\/strong> Edi\u00e7\u00e3o: A\u00e9cio Amado VIA: EBC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Essa atitude pode aumentar em 24% a seguran\u00e7a do menor O melhor local para instalar um dispositivo de&#8230;<\/p>","protected":false},"author":1,"featured_media":1375,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[1],"tags":[24,25,23],"location":[],"class_list":["post-1374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-criancas","tag-seguranca","tag-transito"],"_links":{"self":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/comments?post=1374"}],"version-history":[{"count":1,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1374\/revisions"}],"predecessor-version":[{"id":1376,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1374\/revisions\/1376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/media\/1375"}],"wp:attachment":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/media?parent=1374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/categories?post=1374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/tags?post=1374"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/location?post=1374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}