{"id":1367,"date":"2025-09-26T15:30:53","date_gmt":"2025-09-26T15:30:53","guid":{"rendered":"https:\/\/www.cinthiacarolina.com\/2cmidia\/?p=1367"},"modified":"2025-09-26T15:31:36","modified_gmt":"2025-09-26T15:31:36","slug":"gol-e-azul-encerram-acordo-de-cooperacao-comercial","status":"publish","type":"post","link":"https:\/\/www.cinthiacarolina.com\/2cmidia\/gol-e-azul-encerram-acordo-de-cooperacao-comercial\/","title":{"rendered":"Gol e Azul encerram acordo de coopera\u00e7\u00e3o comercial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Cade fez questionamentos sobre a parceria entre as duas empresas<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1170\" height=\"700\" src=\"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/avioes-aeroporto_mcamgo_abr_290720221818-13.webp\" alt=\"\" class=\"wp-image-1368\" srcset=\"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/avioes-aeroporto_mcamgo_abr_290720221818-13.webp 1170w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/avioes-aeroporto_mcamgo_abr_290720221818-13-570x341.webp 570w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/avioes-aeroporto_mcamgo_abr_290720221818-13-768x459.webp 768w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/avioes-aeroporto_mcamgo_abr_290720221818-13-90x54.webp 90w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/avioes-aeroporto_mcamgo_abr_290720221818-13-320x191.webp 320w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/avioes-aeroporto_mcamgo_abr_290720221818-13-560x335.webp 560w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/avioes-aeroporto_mcamgo_abr_290720221818-13-782x468.webp 782w, https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-content\/uploads\/2025\/09\/avioes-aeroporto_mcamgo_abr_290720221818-13-1136x680.webp 1136w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A Gol Linhas A\u00e9reas anunciou, por meio da Abras Group, sua&nbsp;<em>holdin<\/em>&nbsp;controladora, o fim do acordo de compartilhamento de voos com a Azul Linhas A\u00e9reas.<\/strong>&nbsp;Firmado em maio de 2024, esse acordo recebeu, no in\u00edcio de setembro, cr\u00edticas do Conselho Administrativo de Defesa Econ\u00f4mica (Cade).<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1660405&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1660405&amp;o=node\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na oportunidade, o&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2025-09\/cade-da-30-dias-para-gol-e-azul-detalharem-acordo-de-cooperacao\" target=\"_blank\" rel=\"noreferrer noopener\">Cade<\/a>&nbsp;pediu detalhamentos sobre como seria a coopera\u00e7\u00e3o entre as duas empresas, visando a amplia\u00e7\u00e3o da conectividade no mercado interno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Gol informou acionistas e mercado sobre a solicita\u00e7\u00e3o da rescis\u00e3o destes acordos com a Azul na noite desta quinta-feira (25).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a empresa,\u00a0<strong>esses acordos tinham por objetivo \u201cestabelecer uma coopera\u00e7\u00e3o comercial via\u00a0<em>codeshare<\/em>\u00a0para conectar suas respectivas malhas a\u00e9reas no Brasil&#8221;.<\/strong><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No documento, a&nbsp;<strong>Abra disse ter se colocado \u00e0 disposi\u00e7\u00e3o para continuar avan\u00e7ando nas discuss\u00f5es \u201crumo a uma combina\u00e7\u00e3o de neg\u00f3cios\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ela acrescentou que, no entanto, \u201cas partes n\u00e3o tiveram discuss\u00f5es significativas ou progrediram em uma poss\u00edvel opera\u00e7\u00e3o de combina\u00e7\u00e3o de neg\u00f3cios\u201d, e que, portanto, estaria \u201cencerrando as discuss\u00f5es com rela\u00e7\u00e3o a uma poss\u00edvel transa\u00e7\u00e3o.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pedro Peduzzi &#8211; Rep\u00f3rter da Ag\u00eancia Brasil<\/strong>, Edi\u00e7\u00e3o: Val\u00e9ria Aguiar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cade fez questionamentos sobre a parceria entre as duas empresas A Gol Linhas A\u00e9reas anunciou, por meio da&#8230;<\/p>","protected":false},"author":1,"featured_media":1368,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[3],"tags":[20,18],"location":[],"class_list":["post-1367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-azul","tag-cooperacao-comercial"],"_links":{"self":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/comments?post=1367"}],"version-history":[{"count":1,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1367\/revisions"}],"predecessor-version":[{"id":1369,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/posts\/1367\/revisions\/1369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/media\/1368"}],"wp:attachment":[{"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/media?parent=1367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/categories?post=1367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/tags?post=1367"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.cinthiacarolina.com\/2cmidia\/wp-json\/wp\/v2\/location?post=1367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}